{"id":469,"count":5,"description":"","link":"https:\/\/efectoambiental.org\/Economiaypolitica\/category\/congreso\/","name":"Congreso","slug":"congreso","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/categories\/469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/posts?categories=469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}