{"id":16,"date":"2024-05-14T03:46:25","date_gmt":"2024-05-14T03:46:25","guid":{"rendered":"https:\/\/efectoambiental.org\/Economiaypolitica\/?p=16"},"modified":"2024-05-16T05:46:31","modified_gmt":"2024-05-16T05:46:31","slug":"resurgir-fortalecidos-evaluacion-de-pobreza-y-equidad-en-el-peru","status":"publish","type":"post","link":"https:\/\/efectoambiental.org\/Economiaypolitica\/resurgir-fortalecidos-evaluacion-de-pobreza-y-equidad-en-el-peru\/","title":{"rendered":"Resurgir fortalecidos: Evaluaci\u00f3n de Pobreza y Equidad en el Per\u00fa"},"content":{"rendered":"<p><strong>El Per\u00fa ha sido uno de los pa\u00edses m\u00e1s afectados por la pandemia de la COVID-19 en t\u00e9rminos de impactos econ\u00f3micos y de salud, y del deterioro de las mejoras sociales alcanzadas durante la d\u00e9cada anterior. <\/strong>A julio de 2022, el Per\u00fa hab\u00eda registrado m\u00e1s de 6,000 muertes por mill\u00f3n de habitantes a causa de la COVID-19, ubic\u00e1ndose entre los pa\u00edses con las tasas de mortalidad m\u00e1s altas per c\u00e1pita debido a la pandemia. La econom\u00eda se contrajo en 11 por ciento en 2020, su mayor ca\u00edda en 30 a\u00f1os y la m\u00e1s grande en Am\u00e9rica Latina ese a\u00f1o. Como resultado, la tasa de pobreza nacional se increment\u00f3 a 30.1 por ciento, un nivel que no se hab\u00eda visto desde 2010, y la pobreza extrema alcanz\u00f3 5.1 por ciento en 2020, comparable con la tasa de 2013. Para fines de 2021 la econom\u00eda se hab\u00eda recuperado, pero la pobreza y la pobreza extrema mantuvieron los niveles de 2012 y 2015, respectivamente. La magnitud de la p\u00e9rdida de bienestar durante la crisis revel\u00f3 la fragilidad de las mejoras sociales alcanzadas en las dos d\u00e9cadas anteriores.<\/p>\n<p><strong>Los altos niveles de informalidad y la limitada protecci\u00f3n social dejaron a los trabajadores desprotegidos ante el choque econ\u00f3mico de la crisis por COVID-19, y millones de personas perdieron sus trabajos.<\/strong> Durante el pico de la pandemia (segundo trimestre de 2020), se perdieron aproximadamente 6.7 millones de puestos de trabajo. Sin embargo, las p\u00e9rdidas econ\u00f3micas variaron ampliamente entre la poblaci\u00f3n ocupada. Los trabajadores independientes y las personas empleadas en empresas peque\u00f1as \u2013mayormente informales\u2013 sufrieron la ca\u00edda m\u00e1s grande en t\u00e9rminos de empleo. Por el contrario, aquellos que pudieron trabajar desde casa y que contaban con conectividad a internet \u2013mayormente formales\u2013 tuvieron menos probabilidad de perder su trabajo. Los j\u00f3venes, con tasas de informalidad m\u00e1s altas en relaci\u00f3n con el resto de la poblaci\u00f3n, perdieron su trabajo a tasas m\u00e1s elevadas. Las mujeres se vieron desproporcionadamente afectadas, ya que abandonaron la fuerza laboral a una tasa m\u00e1s alta que los hombres, principalmente porque proporcionaron cuidado a ni\u00f1os y ancianos en los hogares.<\/p>\n<p><strong>A pesar de la importante respuesta del gobierno a la crisis, el Per\u00fa afronta una mayor pobreza ahora que antes de la pandemia. En el pico de la pandemia, el sistema de salud colaps\u00f3, y nadie, sin importar su capacidad de pago, pudo acceder a una atenci\u00f3n adecuada.<\/strong> Diversos elementos de la respuesta gubernamental sirvieron como amortiguadores contra la p\u00e9rdida de ingresos, evitando un aumento de la tasa de pobreza de 3.6 puntos porcentuales adicionales. Sin embargo, si bien el paquete de mitigaci\u00f3n en el Per\u00fa fue uno de los m\u00e1s grandes de la regi\u00f3n, \u00e9ste result\u00f3 insuficiente para proteger a los pobres y vulnerables y pobres de caer (o caer a\u00fan m\u00e1s) en la pobreza.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: El Banco Mundial en Per\u00fa<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-80\" src=\"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-content\/uploads\/2024\/05\/banco-mudial.png\" alt=\"\" width=\"206\" height=\"60\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Per\u00fa ha sido uno de los pa\u00edses m\u00e1s afectados por la pandemia de la COVID-19 en t\u00e9rminos de impactos econ\u00f3micos y de salud, y del deterioro de las mejoras sociales alcanzadas durante la d\u00e9cada anterior. A julio de 2022, el Per\u00fa hab\u00eda registrado m\u00e1s de 6,000 muertes por mill\u00f3n de habitantes a causa de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_crdt_document":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-16","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"featured_image_urls":{"full":["https:\/\/efectoambiental.org\/Economiaypolitica\/wp-content\/uploads\/2024\/05\/PE-Peru-Poverty-Assesment-Informe-Pobreza-y-Equidad-Resurgir-Fortalecidos-portada-780x439-1.webp",780,439,false],"thumbnail":["https:\/\/efectoambiental.org\/Economiaypolitica\/wp-content\/uploads\/2024\/05\/PE-Peru-Poverty-Assesment-Informe-Pobreza-y-Equidad-Resurgir-Fortalecidos-portada-780x439-1-150x150.webp",150,150,true],"medium":["https:\/\/efectoambiental.org\/Economiaypolitica\/wp-content\/uploads\/2024\/05\/PE-Peru-Poverty-Assesment-Informe-Pobreza-y-Equidad-Resurgir-Fortalecidos-portada-780x439-1-300x169.webp",300,169,true],"medium_large":["https:\/\/efectoambiental.org\/Economiaypolitica\/wp-content\/uploads\/2024\/05\/PE-Peru-Poverty-Assesment-Informe-Pobreza-y-Equidad-Resurgir-Fortalecidos-portada-780x439-1-768x432.webp",640,360,true],"large":["https:\/\/efectoambiental.org\/Economiaypolitica\/wp-content\/uploads\/2024\/05\/PE-Peru-Poverty-Assesment-Informe-Pobreza-y-Equidad-Resurgir-Fortalecidos-portada-780x439-1.webp",640,360,false],"1536x1536":["https:\/\/efectoambiental.org\/Economiaypolitica\/wp-content\/uploads\/2024\/05\/PE-Peru-Poverty-Assesment-Informe-Pobreza-y-Equidad-Resurgir-Fortalecidos-portada-780x439-1.webp",780,439,false],"2048x2048":["https:\/\/efectoambiental.org\/Economiaypolitica\/wp-content\/uploads\/2024\/05\/PE-Peru-Poverty-Assesment-Informe-Pobreza-y-Equidad-Resurgir-Fortalecidos-portada-780x439-1.webp",780,439,false],"yarpp-thumbnail":["https:\/\/efectoambiental.org\/Economiaypolitica\/wp-content\/uploads\/2024\/05\/PE-Peru-Poverty-Assesment-Informe-Pobreza-y-Equidad-Resurgir-Fortalecidos-portada-780x439-1.webp",120,68,false]},"author_info":{"display_name":"admin","author_link":"https:\/\/efectoambiental.org\/Economiaypolitica\/author\/admin\/"},"category_info":"<a href=\"https:\/\/efectoambiental.org\/Economiaypolitica\/category\/economia\/\" rel=\"category tag\">Economia<\/a>","tag_info":"Economia","comment_count":"0","_links":{"self":[{"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/posts\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/comments?post=16"}],"version-history":[{"count":2,"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/posts\/16\/revisions"}],"predecessor-version":[{"id":85,"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/posts\/16\/revisions\/85"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/media\/17"}],"wp:attachment":[{"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/media?parent=16"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/categories?post=16"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efectoambiental.org\/Economiaypolitica\/wp-json\/wp\/v2\/tags?post=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}