{"id":240,"count":12,"description":"OC\u00c9ANOS","link":"https:\/\/efectoambiental.org\/Noticias\/category\/oceanos\/","name":"Oc\u00e9anos","slug":"oceanos","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/categories\/240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts?categories=240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}