{"id":1147,"date":"2021-08-30T23:03:52","date_gmt":"2021-08-30T23:03:52","guid":{"rendered":"https:\/\/efectoambiental.org\/Noticias\/?p=1147"},"modified":"2021-08-30T23:03:52","modified_gmt":"2021-08-30T23:03:52","slug":"el-mundo-pone-fin-a-la-era-de-la-gasolina-con-plomo","status":"publish","type":"post","link":"https:\/\/efectoambiental.org\/Noticias\/2021\/08\/30\/el-mundo-pone-fin-a-la-era-de-la-gasolina-con-plomo\/","title":{"rendered":"El mundo pone fin a la era de la gasolina con plomo"},"content":{"rendered":"<p>y elimina una grave amenaza para la salud humana y ambiental<\/p>\n<p>&nbsp;<\/p>\n<section class=\"region region-content\">\n<section id=\"block-system-main\" class=\"block block-system clearfix\">\n<div id=\"node-1496062\" class=\"node node-news-story node-full clearfix\">\n<div class=\"content\">\n<div class=\"field field-name-field-news-story-lead field-type-text-long field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>La erradicaci\u00f3n oficial del uso de la gasolina con plomo evitar\u00e1 m\u00e1s de 1,2 millones de muertes prematuras y ahorrar\u00e1 US$ 2,45 billones al a\u00f1o. Este hito se logra tras una campa\u00f1a de 19 a\u00f1os liderada por la agencia de la ONU encargada de cuidar el medio ambiente. Ant\u00f3nio Guterres asegura que es el \u201c\u00e9xito de un esfuerzo global conjunto\u201d.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"paragraphs-items paragraphs-items-field-news-story paragraphs-items-field-news-story-full paragraphs-items-full\">\n<div class=\"field field-name-field-news-story field-type-paragraphs field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<div class=\"entity entity-paragraphs-item paragraphs-item-one-column-text\">\n<div class=\"content\">\n<div class=\"field field-name-field-text-column field-type-text-long field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>El uso de la gasolina con plomo lleg\u00f3 a su fin en todo el mundo luego de que este combustible altamente contaminante se dejara de ofrecer en las estaciones de servicio de Argelia en julio pasado. Este hito global se alcanza tras una campa\u00f1a de casi dos d\u00e9cadas de la\u00a0<a href=\"https:\/\/www.unep.org\/explore-topics\/transport\/what-we-do\/partnership-clean-fuels-and-vehicles\">Alianza para combustibles y veh\u00edculos limpios<\/a>\u00a0liderada por el\u00a0<a class=\"word-link\" href=\"https:\/\/www.unenvironment.org\/es\">Programa de las Naciones Unidas para el Medio Ambiente<\/a>\u00a0(PNUMA).<\/p>\n<p>Desde 1922, la adici\u00f3n de tetraetilo de plomo a la gasolina con el fin de mejorar el rendimiento de los motores\u00a0<a href=\"https:\/\/www.who.int\/bulletin\/archives\/80(10)768.pdf\">se ha convertido en una cat\u00e1strofe para el medio ambiente y la salud p\u00fablica<\/a>. En la d\u00e9cada de 1970, casi toda la gasolina producida en el mundo conten\u00eda plomo y, en 2002, cuando la agencia de la ONU comenz\u00f3 su campa\u00f1a para eliminar el plomo en la gasolina, esta era una de las amenazas ambientales m\u00e1s graves para la salud humana.<\/p>\n<h2>Un siglo contaminando el aire, el suelo y el agua<\/h2>\n<p>La erradicaci\u00f3n mundial del uso de la gasolina con plomo se logr\u00f3 este a\u00f1o, luego de que este peligroso metal contaminara el aire, el polvo, el suelo, el agua potable y los cultivos alimentarios durante la mayor parte de un siglo.<\/p>\n<p><strong>La gasolina con plomo causa enfermedades card\u00edacas, accidentes cerebrovasculares y c\u00e1ncer<\/strong>. Tambi\u00e9n afecta el desarrollo del cerebro humano,\u00a0<a href=\"https:\/\/www.unicef.org\/es\/comunicados-prensa\/un-tercio-de-los-ni%C3%B1os-del-mundo-est%C3%A1-intoxicado-por-plomo-seg%C3%BAn-un-nuevo\">especialmente de los ni\u00f1os<\/a>.\u00a0<a href=\"https:\/\/www.motherjones.com\/environment\/2016\/02\/lead-exposure-gasoline-crime-increase-children-health\/\">Estudios<\/a>\u00a0sugieren que la exposici\u00f3n a este contaminante puede reducir el coeficiente intelectual entre 5 y 10 puntos.<\/p>\n<p>Se\u00a0<a href=\"http:\/\/www.csun.edu\/~vchsc006\/lead.pdf\">ha estimado<\/a>\u00a0que prohibir el uso de gasolina con plomo evita m\u00e1s de 1,2 millones de muertes prematuras al a\u00f1o, aumenta el coeficiente intelectual de los ni\u00f1os, reduce las tasas de delincuencia e implica ahorros de hasta 2,45 billones para la econom\u00eda mundial.<\/p>\n<p>\u201cLa aplicaci\u00f3n exitosa de la prohibici\u00f3n de la gasolina con plomo es un gran hito para la salud mundial y para el medio ambiente\u201d, dijo Inger Andersen, directora ejecutiva del PNUMA.<\/p>\n<p>\u00abDespu\u00e9s de un siglo de muertes y enfermedades que afectaron a cientos de millones de personas y degradaron el medio ambiente mundial,\u00a0<strong>estamos determinados a enderezar la trayectoria de la humanidad con una transici\u00f3n acelerada hacia la movilidad el\u00e9ctrica<\/strong>\u00a0y el uso de veh\u00edculos limpios\u00bb, a\u00f1adi\u00f3 Andersen.<\/p>\n<div class=\"dnd-widget-wrapper context-un_news_full_width type-image\">\n<div class=\"dnd-atom-rendered\"><picture><source srcset=\"\" media=\"(max-width : 992px)\" \/><source srcset=\"\" media=\"(max-width : 480px)\" \/><source srcset=\"https:\/\/global.unitednations.entermediadb.net\/assets\/mediadb\/services\/module\/asset\/downloads\/preset\/Libraries\/Production+Library\/24-11-2020-UNICEF-UNI38180-Smog-Shanghai.jpg\/image770x420cropped.jpg\" media=\"(max-width : 768px)\" \/><source srcset=\"https:\/\/global.unitednations.entermediadb.net\/assets\/mediadb\/services\/module\/asset\/downloads\/preset\/Libraries\/Production+Library\/24-11-2020-UNICEF-UNI38180-Smog-Shanghai.jpg\/image1170x530cropped.jpg\" media=\"(max-width : 1200px) \" \/><img decoding=\"async\" class=\"img-responsive\" title=\"La contaminaci\u00f3n sobre los cielos de la ciudad china de Shanghai oculta el atardecer.\" src=\"https:\/\/global.unitednations.entermediadb.net\/assets\/mediadb\/services\/module\/asset\/downloads\/preset\/Libraries\/Production+Library\/24-11-2020-UNICEF-UNI38180-Smog-Shanghai.jpg\/image1170x530cropped.jpg\" alt=\"La contaminaci\u00f3n sobre los cielos de la ciudad china de Shanghai oculta el atardecer.\" width=\"100%\" height=\"\" \/><\/picture>\n<div class=\"field-name-field-scald-photo-credit field field-name-scald-authors field-type-taxonomy-term-reference field-label-hidden\"><span class=\"un-news-full-width scald-credit\">UNICEF\/Roger LeMoyne<\/span><\/div>\n<div class=\"field-name-field-scald-photo-caption field field-name-field-title field-type-text field-label-hidden\"><span class=\"un-news-full-width scald-caption\">La contaminaci\u00f3n sobre los cielos de la ciudad china de Shanghai oculta el atardecer.<\/span><\/div>\n<\/div>\n<\/div>\n<h2>Una alianza para crear conciencia<\/h2>\n<p>En la d\u00e9cada de 1980, la mayor\u00eda de los pa\u00edses de ingresos altos hab\u00edan prohibido el uso de la gasolina con plomo, sin embargo, en 2002, casi todos los pa\u00edses de ingresos bajos y medianos \u2014incluidos algunos miembros de la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3micos (OCDE)\u2014 todav\u00eda utilizaban gasolina con plomo.<\/p>\n<p>La\u00a0<a href=\"https:\/\/www.unep.org\/explore-topics\/transport\/what-we-do\/partnership-clean-fuels-and-vehicles\">Alianza para combustibles y veh\u00edculos limpios<\/a>\u00a0es una asociaci\u00f3n p\u00fablico-privada que reuni\u00f3 a todas las partes interesadas al brindar asistencia t\u00e9cnica,\u00a0<strong>crear conciencia, superar los desaf\u00edos y la resistencia de los comerciantes del petr\u00f3leo y productores de plomo locales<\/strong>, e invertir en mejoras en las refiner\u00edas.<\/p>\n<p>El Kwaku Afriyie, ministro de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n Ambiental de Ghana, dijo: \u201cCuando la ONU comenz\u00f3 a trabajar con gobiernos y empresas para eliminar gradualmente el plomo de la gasolina, las naciones del \u00c1frica subsahariana aprovecharon con entusiasmo esta oportunidad. Ghana fue uno de los cinco pa\u00edses de \u00c1frica Occidental que se unieron a los primeros talleres y declaraciones subregionales. Tras las campa\u00f1as en los medios de comunicaci\u00f3n de la alianza, los informes, los estudios, la exposici\u00f3n de las ilegalidades y las pruebas p\u00fablicas realizadas para revelar los altos niveles de plomo en la sangre de la poblaci\u00f3n, Ghana se mostr\u00f3 cada vez m\u00e1s decidida a liberar su combustible de plomo\u00bb.<\/p>\n<p>A pesar de este progreso,\u00a0<strong>la flota de veh\u00edculos mundial, en r\u00e1pido crecimiento, contin\u00faa contribuyendo a las amenazas de la contaminaci\u00f3n del aire, el agua y el suelo<\/strong>, as\u00ed como a la crisis clim\u00e1tica global. El sector del transporte es responsable de casi\u00a0<a href=\"https:\/\/www.ipcc.ch\/site\/assets\/uploads\/2018\/02\/ipcc_wg3_ar5_chapter8.pdf\">una cuarta parte<\/a>\u00a0de las emisiones globales de gases de efecto de invernadero relacionados con la energ\u00eda y se prev\u00e9 que esta proporci\u00f3n aumente a un tercio para 2050.<\/p>\n<p>Si bien muchos pa\u00edses ya han comenzado la transici\u00f3n hacia la movilidad el\u00e9ctrica,\u00a0<a href=\"https:\/\/openknowledge.worldbank.org\/bitstream\/handle\/10986\/28542\/120500.pdf?sequence=6\">1200 millones de veh\u00edculos nuevos entrar\u00e1n en las carreteras en las pr\u00f3ximas d\u00e9cadas<\/a>, y muchos de ellos utilizar\u00e1n combustibles f\u00f3siles, especialmente en los pa\u00edses en desarrollo. Adem\u00e1s,\u00a0<a href=\"https:\/\/www.unep.org\/es\/noticias-y-reportajes\/comunicado-de-prensa\/nuevo-informe-de-la-onu-destaca-los-impactos-ambientales\">millones de veh\u00edculos usados de mala calidad<\/a>\u00a0podr\u00edan ser exportados desde Europa, Estados Unidos y Jap\u00f3n a pa\u00edses de ingresos medios y bajos, una pr\u00e1ctica que contribuye al calentamiento del planeta y la contaminaci\u00f3n del aire, y tiene v\u00ednculos con la incidencia de los accidentes de tr\u00e1nsito.<\/p>\n<p>\u00abEl hecho de que una alianza multisectorial respaldada por la ONU haya podido librar al mundo de este combustible t\u00f3xico es testimonio del poder del multilateralismo para mover el mundo hacia la sostenibilidad y un futuro m\u00e1s limpio y verde\u00bb, asegur\u00f3 Inger Andersen.<\/p>\n<h2>Asegurar combustibles m\u00e1s limpios y reducir las emisiones<\/h2>\n<p>\u00abInstamos a las mismas partes interesadas a inspirarse en este enorme logro para garantizar que, ahora que tenemos combustibles m\u00e1s limpios, tambi\u00e9n adoptemos mejores est\u00e1ndares vehiculares a nivel mundial:\u00a0<strong>la combinaci\u00f3n de combustibles y veh\u00edculos m\u00e1s limpios puede reducir las emisiones en m\u00e1s de un 80%<\/strong>\u00ab, dijo Andersen.<\/p>\n<p>Si bien el mundo ha eliminado la mayor fuente de contaminaci\u00f3n por plomo, a\u00fan se necesitan acciones urgentes para\u00a0<strong>detener la contaminaci\u00f3n por este metal proveniente de otras fuentes<\/strong>, como las pinturas, las bater\u00edas y los art\u00edculos dom\u00e9sticos que contienen este t\u00f3xico.<\/p>\n<p>Se espera que el fin de la gasolina con plomo apoye el cumplimiento de m\u00faltiples\u00a0<a class=\"word-link\" href=\"https:\/\/news.un.org\/es\/news\/topic\/sdgs\">Objetivos de Desarrollo Sostenible<\/a>, incluidos el n\u00famero 3 sobre salud y bienestar; el n\u00famero 6 sobre agua limpia y saneamiento; el 7 sobre energ\u00eda asequible y no contaminante; el 11 sobre ciudades y comunidades sostenibles; el 13 sobre acci\u00f3n por el clima; y el 15 sobre la vida de los ecosistemas terrestres.<\/p>\n<p>Tambi\u00e9n ofrece una oportunidad para\u00a0<a href=\"https:\/\/www.unep.org\/es\/resources\/ecosystem-restoration-people-nature-climate\">restaurar ecosistemas<\/a>, especialmente en entornos urbanos que han sido particularmente degradados por este contaminante t\u00f3xico. Finalmente, es un gran progreso previo al\u00a0<a href=\"https:\/\/www.cleanairblueskies.org\/es\">D\u00eda Internacional del Aire Limpio por un cielo azul<\/a>, que se celebra el 7 de septiembre.<\/p>\n<div class=\"dnd-widget-wrapper context-un_news_large_uncropped type-image\">\n<div class=\"dnd-atom-rendered\"><img decoding=\"async\" class=\"img-responsive\" title=\"Tras veinte a\u00f1os de campa\u00f1a, el uso de la gasolina con plomo se ha eliminado en todo el mundo.\" src=\"https:\/\/global.unitednations.entermediadb.net\/assets\/mediadb\/services\/module\/asset\/downloads\/preset\/Libraries\/Production+Library\/30-08-2021_UN-News_Chad.jpg\/image1024x768.jpg\" alt=\"Tras veinte a\u00f1os de campa\u00f1a, el uso de la gasolina con plomo se ha eliminado en todo el mundo.\" width=\"\" height=\"\" \/><\/p>\n<div class=\"field-name-field-scald-photo-credit field field-name-scald-authors field-type-taxonomy-term-reference field-label-hidden\"><span class=\"un-news-large-uncropped scald-credit\">ONU Noticias\/Daniel Dickinson<\/span><\/div>\n<div class=\"field-name-field-scald-photo-caption field field-name-field-title field-type-text field-label-hidden\"><span class=\"un-news-large-uncropped scald-caption\">Tras veinte a\u00f1os de campa\u00f1a, el uso de la gasolina con plomo se ha eliminado en todo el mundo.<\/span><\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h3>Un \u00e9xito del multilateralismo<\/h3>\n<p>En su mensaje por la consecuci\u00f3n de este hito multilateral, el\u00a0<a class=\"word-link\" href=\"https:\/\/www.un.org\/sg\/es\">Secretario General<\/a>\u00a0de la ONU lo defini\u00f3 como \u201cla culminaci\u00f3n de un esfuerzo global conjunto\u201d y se\u00f1al\u00f3 que deshacerse de la gasolina con plomo sirve para\u00a0<strong>librarse de \u201cuna gran amenaza para la salud humana y planetaria\u201d<\/strong>.<\/p>\n<p>Ant\u00f3nio Guterres record\u00f3 que al inicio de la campa\u00f1a para eliminar el plomo hab\u00eda 86 pa\u00edses us\u00e1ndolo y que hoy ya no queda ninguno \u201c<strong>gracias a la cooperaci\u00f3n de los gobiernos de las naciones en desarrollo, miles de empresas y millones de ciudadanos de a pie<\/strong>\u201d.<\/p>\n<p>El titular de la ONU destac\u00f3 que ahora es necesario mostrar el mismo tipo de compromiso con la alteraci\u00f3n del clima, la p\u00e9rdida de biodiversidad y la contaminaci\u00f3n y pasar de los combustibles f\u00f3siles a las energ\u00edas renovables.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/section>\n<section class=\"region region-after-content\">\n<section id=\"block-nodeblock-1448902\" class=\"block block-nodeblock clearfix\">\n<div id=\"node-1448902\" class=\"node node-promo-banner node-full clearfix\">\n<div class=\"content\">\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<h2 class=\"block-title\"><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>y elimina una grave amenaza para la salud humana y ambiental &nbsp; La erradicaci\u00f3n oficial<\/p>\n","protected":false},"author":1,"featured_media":1148,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[264,265],"tags":[414,287,413,410,412,411],"class_list":["post-1147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cambio-climatico","category-medioambiente","tag-accidentes-cerebrovasculares","tag-cancer","tag-enfermedades-cardiacas","tag-gasolina-con-plomo","tag-onu","tag-pnuma"],"_links":{"self":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/comments?post=1147"}],"version-history":[{"count":1,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1147\/revisions"}],"predecessor-version":[{"id":1149,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1147\/revisions\/1149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media\/1148"}],"wp:attachment":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media?parent=1147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/categories?post=1147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/tags?post=1147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}