{"id":1381,"date":"2022-02-23T23:47:08","date_gmt":"2022-02-23T23:47:08","guid":{"rendered":"https:\/\/efectoambiental.org\/Noticias\/?p=1381"},"modified":"2022-02-23T23:47:08","modified_gmt":"2022-02-23T23:47:08","slug":"reunion-de-coordinacion-la-hora-del-planeta-%f0%9f%8c%b3","status":"publish","type":"post","link":"https:\/\/efectoambiental.org\/Noticias\/2022\/02\/23\/reunion-de-coordinacion-la-hora-del-planeta-%f0%9f%8c%b3\/","title":{"rendered":"Reuni\u00f3n de coordinaci\u00f3n &#8211; La Hora del Planeta \ud83c\udf33"},"content":{"rendered":"<p>Estimado(a):<br \/>\n\u00a1Gracias por cada a\u00f1o sumarte al movimiento ambiental m\u00e1s grande del mundo! Los \u00faltimos a\u00f1os han sido a\u00f1os retadores para todos y valoramos tu entusiasmo para acompa\u00f1arnos como aliado de La Hora del Planeta. Sabemos que nuestra salud est\u00e1 ligada a la salud del planeta, por ello, transmitir este mensaje es clave para que entendamos la importancia de cuidar la naturaleza.<\/p>\n<p>Este 2022, La Hora del Planeta se celebrar\u00e1 en sus casas y virtualmente el S\u00e1bado 26 de Marzo a las 8:30p.m.<\/p>\n<p>Para que conozcan c\u00f3mo poder participar, hemos preparado diversas actividades que podr\u00e1n realizar desde casa e invitar a sus\u00a0familiares, amigos, colaboradores y aliados a unirse.\u00a0<strong>Si deseas conocer en detalle cada una de las actividades, te invitamos a\u00a0unirte\u00a0al ZOOM seg\u00fan el tipo de organizaci\u00f3n a la que perteneces.<\/strong><\/p>\n<p><strong>Entidades Gubernamentales y Municipios<\/strong><\/p>\n<ul>\n<li><strong>D\u00eda:\u00a0<\/strong>Martes 1 de Marzo<\/li>\n<li><strong>Hora:\u00a0<\/strong><strong>9 a.m<\/strong><\/li>\n<li><strong>Link:\u00a0<a href=\"https:\/\/panda.us7.list-manage.com\/track\/click?u=58dc95c5b37f242e3f3b76a72&amp;id=00aaa525c8&amp;e=297ce46a87\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/bit.ly\/350osg8<\/a><\/strong><\/li>\n<\/ul>\n<p><strong>Empresas y ONGs<\/strong><\/p>\n<ul>\n<li><strong>D\u00eda:\u00a0<\/strong>Martes 1 de Marzo<\/li>\n<li><strong>Hora:\u00a0<\/strong><strong>12 p.m<\/strong><\/li>\n<li><strong>Link:\u00a0<a href=\"https:\/\/panda.us7.list-manage.com\/track\/click?u=58dc95c5b37f242e3f3b76a72&amp;id=f93763447a&amp;e=297ce46a87\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/bit.ly\/3BI6pas<\/a><\/strong><\/li>\n<\/ul>\n<p><strong>Centros Educativos<\/strong><\/p>\n<ul>\n<li><strong>D\u00eda:\u00a0<\/strong>Martes 1 de Marzo<\/li>\n<li><strong>Hora:\u00a0<\/strong><strong>5 p.m<\/strong><\/li>\n<li><strong>Link:<\/strong>\u00a0<strong><a href=\"https:\/\/panda.us7.list-manage.com\/track\/click?u=58dc95c5b37f242e3f3b76a72&amp;id=d915a8c1b4&amp;e=297ce46a87\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/bit.ly\/3sejANx<\/a><\/strong><\/li>\n<\/ul>\n<p>Saludos cordiales,<\/p>\n<p><strong>WWF-Per\u00fa<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mcusercontent.com\/58dc95c5b37f242e3f3b76a72\/images\/ec2539fc-26f3-4c27-8c37-999d4b139323.jpg\" width=\"100\" height=\"112\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimado(a): \u00a1Gracias por cada a\u00f1o sumarte al movimiento ambiental m\u00e1s grande del mundo! Los \u00faltimos<\/p>\n","protected":false},"author":1,"featured_media":1382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[241],"tags":[701,700,609],"class_list":["post-1381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wwf","tag-la-hora-del-planeta-","tag-reunion-de-coordinacion","tag-wwf-peru"],"_links":{"self":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/comments?post=1381"}],"version-history":[{"count":1,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1381\/revisions"}],"predecessor-version":[{"id":1383,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1381\/revisions\/1383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media\/1382"}],"wp:attachment":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media?parent=1381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/categories?post=1381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/tags?post=1381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}