{"id":1573,"date":"2022-06-13T22:49:02","date_gmt":"2022-06-13T22:49:02","guid":{"rendered":"https:\/\/efectoambiental.org\/Noticias\/?p=1573"},"modified":"2022-06-13T22:49:02","modified_gmt":"2022-06-13T22:49:02","slug":"bachelet-pide-resolver-las-circunstancias-que-provocan-las-crisis-el-hambre-y-la-pobreza","status":"publish","type":"post","link":"https:\/\/efectoambiental.org\/Noticias\/2022\/06\/13\/bachelet-pide-resolver-las-circunstancias-que-provocan-las-crisis-el-hambre-y-la-pobreza\/","title":{"rendered":"Bachelet pide resolver las circunstancias que provocan las crisis, el hambre y la pobreza"},"content":{"rendered":"<p>La m\u00e1xima responsable de derechos humanos de la ONU recuerda que 1200 millones de personas viven en pa\u00edses que est\u00e1n gravemente expuestos y son vulnerables a una triple crisis: financiera, alimentaria y energ\u00e9tica. Michelle Bachelet anuncia que no se presentar\u00e1 a un segundo mandato como Alta Comisionada.<\/p>\n<p>Ante la actual situaci\u00f3n de crisis alimentaria, energ\u00e9tica y financiera mundial que puede sumir a millones de personas en una situaci\u00f3n de inseguridad alimentaria y pobreza y con las crecientes desigualdades entre pa\u00edses, la Alta Comisionada de la ONU para los Derechos Humanos pidi\u00f3 este lunes una actuaci\u00f3n m\u00e1s firme e inmediata para solucionar los impactos de estos desequilibrios y as\u00ed limitar el sufrimiento humano.<\/p>\n<p>\u201cPero esto no es suficiente. Tenemos que dedicarnos a resolver las circunstancias que provocan estas crisis. Insto a que, precisamente en este momento de grave y profunda amenaza, sigamos el camino al que nos hab\u00edamos comprometido tras la pandemia de COVID-19\u201d, afirm\u00f3 Michelle Bachelet durante una actualizaci\u00f3n oral sobre la evoluci\u00f3n de los derechos humanos en el mundo y las actividades de su Oficina en el Consejo de Derechos Humanos.<\/p>\n<p>Aludiendo a un ejemplo reciente, Bachelet record\u00f3 que para evitar las devastadoras consecuencias que crearon las pol\u00edticas de austeridad tras la crisis financiera de 2008, la comunidad internacional acord\u00f3 cambiar de rumbo y construir sociedades capaces de transformarse y encaminadas a econom\u00edas m\u00e1s verdes y resistentes a las crisis.<\/p>\n<p>\u201cAhora nos enfrentamos a una prueba vital de ese compromiso. Y tenemos que cumplirla. La Agenda 2030 y el Acuerdo de Par\u00eds deben seguir siendo nuestro modelo para alcanzar este objetivo. En los ocho a\u00f1os que nos quedan debemos tomar medidas valientes y urgentes para generar el cambio transformador que se necesita para cumplir con los Objetivos de Desarrollo Sostenible\u201d, destac\u00f3.<\/p>\n<p>Para ello, y tomando como fuente de inspiraci\u00f3n el informe del Secretario General Nuestra Agenda Com\u00fan, que refleja la visi\u00f3n del Secretario General sobre el futuro de la cooperaci\u00f3n mundial y la revitalizaci\u00f3n del multilateralismo, el Llamamiento a la Acci\u00f3n en favor de los derechos humanos de Guterres y el proprio trabajo de su Oficina, Bachelet apunt\u00f3 cuatro \u00e1reas de actuaci\u00f3n que espera sirvan de orientaci\u00f3n ante las crisis actuales.<\/p>\n<p>Acabar con las disparidades y la marginaci\u00f3n<br \/>\nEn primer lugar, indic\u00f3 la necesidad de \u201catajar la desigualdad y la discriminaci\u00f3n\u201d y como muestra cit\u00f3 a un estudio que estima que las actuales desigualdades a nivel mundial son tan grandes como las que hab\u00eda a principios del siglo XX.<\/p>\n<p>\u201cEl Banco Mundial ha previsto que en 2022 habr\u00e1 198 millones m\u00e1s de personas en situaci\u00f3n de pobreza extrema debido a la COVID-19. Ahora se calcula que s\u00f3lo los precios de los alimentos a nivel mundial a\u00f1adir\u00e1n otros 65 millones de personas a ese total\u201d, alert\u00f3.<\/p>\n<p>Al mismo tiempo, destac\u00f3 que, aunque la pandemia produjo p\u00e9rdidas de ingresos en todas las capas de la sociedad, \u201cel 20% m\u00e1s pobre experiment\u00f3 el mayor descenso de ganancias. Y el 40% m\u00e1s pobre no ha empezado a recuperarse de sus p\u00e9rdidas de ingresos\u201d. A este factor se le ha de a\u00f1adir la crisis clim\u00e1tica donde \u201cde nuevo los m\u00e1s pobres y vulnerables son los que se llevan la peor parte\u201d.<\/p>\n<p>A consecuencia de este c\u00famulo de factores, explic\u00f3 que la \u201ccapacidad de las personas para soportar otra crisis se est\u00e1 reduciendo a\u00fan m\u00e1s\u201d, y que ante este escenario \u201cdebemos seguir comprometi\u00e9ndonos a corregir las desigualdades y la discriminaci\u00f3n\u201d.<\/p>\n<p>El escenario mundial actual no conduce al alcance de los ODS. Imagen: Informo Objetivos de Desarrollo Sostenible<br \/>\nEl escenario mundial actual no conduce al alcance de los ODS. Imagen: Informo Objetivos de Desarrollo Sostenible<br \/>\nLograr los Objetivos de Desarrollo Sostenibles est\u00e1 cada vez m\u00e1s lejos<br \/>\nLos dos siguientes factores que destac\u00f3 fueron la necesidad de integrar las garant\u00edas fundamentales en los presupuestos nacionales de cada pa\u00eds, ya que \u201csi se dise\u00f1an y ejecutan con un enfoque basado en los derechos humanos, pueden ser una poderosa herramienta para el progreso de los Objetivos de Desarrollo Sostenible\u201d, y la necesidad de lograr una mayor cooperaci\u00f3n y solidaridad internacional.<\/p>\n<p>\u201cLa brecha de financiaci\u00f3n para alcanzar los Objetivos de Desarrollo Sostenible se ha ampliado en m\u00e1s de un 70% hasta alcanzar un importe anual de 4,3 billones de d\u00f3lares\u201d, se\u00f1al\u00f3.<\/p>\n<p>Ante este escenario, manifest\u00f3 que la diferencia requiere que los pa\u00edses movilicen recursos p\u00fablicos y privados tanto a nivel nacional como internacional.<\/p>\n<p>\u201cSin embargo, la espiral de la deuda y las perspectivas inciertas del panorama econ\u00f3mico -que se agravar\u00e1n a\u00fan m\u00e1s en el contexto actual- est\u00e1n frenando a muchos pa\u00edses en desarrollo. Se calcula que en 2022 estos pa\u00edses necesitar\u00e1n 311.000 millones de d\u00f3lares para atender el servicio de la deuda externa p\u00fablica, lo que supone el 13,6% de los ingresos p\u00fablicos\u201d, expuso.<\/p>\n<p>En este contexto, inst\u00f3 a los pa\u00edses a redoblar los esfuerzos para alcanzar el objetivo del 0,7% de la asistencia oficial para el desarrollo, \u201cpartiendo de la base de que el gasto social de hoy produce mejores resultados sociales en el futuro\u201d.<\/p>\n<p>Por \u00faltimo, destac\u00f3 la importancia de contar con un espacio p\u00fablico que sirva para construir la capacidad de recuperaci\u00f3n necesaria en tiempos de crisis.<\/p>\n<p>\u201cS\u00e9 y he visto que una vida digna significa asegurar los derechos al trabajo, a la vivienda, a la alimentaci\u00f3n, al agua y al saneamiento\u201d, afirm\u00f3.<\/p>\n<p>Y a\u00f1adi\u00f3 \u201cque estos derechos s\u00f3lo pueden protegerse y cumplirse si las personas tienen el espacio para expresar sus opiniones y exigir el cambio que desean ver\u201d, y que juntos \u201cson la esencia de una sociedad vibrante, justa y pac\u00edfica\u201d.<\/p>\n<p>Situaci\u00f3n en Am\u00e9rica Latina<br \/>\nCon relaci\u00f3n a Am\u00e9rica Latina, constat\u00f3 un patr\u00f3n de ataques contra la labor de los funcionarios del sistema de justicia en Guatemala, \u201ccon casos emblem\u00e1ticos de graves violaciones a los derechos humanos, corrupci\u00f3n e impunidad\u201d.<\/p>\n<p>En consecuencia, dijo que \u201cel Estado debe garantizar la independencia de las instituciones judiciales y la protecci\u00f3n de los operadores de justicia\u201d.<\/p>\n<p>Respecto a M\u00e9xico, abog\u00f3 por el fortalecimiento de las instituciones civiles para establecer un plan ordenado de retirada de los militares de las tareas de seguridad p\u00fablica.<\/p>\n<p>Destac\u00f3 que las medidas adoptadas en El Salvador en el marco del estado de excepci\u00f3n para luchar contra la violencia de las bandas, junto a las posteriores modificaciones del derecho penal, aumentan el riesgo de detenci\u00f3n arbitraria y tortura de los detenidos.<\/p>\n<p>\u201cM\u00e1s de 38.000 personas han sido detenidas en el contexto del estado de excepci\u00f3n, lo que suscita preocupaci\u00f3n por el respeto a las garant\u00edas del debido proceso. Son especialmente preocupantes las al menos 21 muertes bajo custodia de las que informan fuentes oficiales\u201d, destac\u00f3.<\/p>\n<p>En cuanto a Colombia, celebr\u00f3 el car\u00e1cter pac\u00edfico y democr\u00e1tico de la primera vuelta de las elecciones presidenciales, y confi\u00f3 en que se mantengan durante la segunda vuelta.<\/p>\n<p>Igualmente, inst\u00f3 a una aplicaci\u00f3n efectiva del Acuerdo de Paz, \u201cen particular el desmantelamiento de los grupos responsables del aumento de la violencia\u201d y acogi\u00f3 con satisfacci\u00f3n los importantes avances en materia de justicia transicional.<\/p>\n<p>Por \u00faltimo, pidi\u00f3 al Estado que asegure mecanismos de justicia transicional independientes y garantice la protecci\u00f3n de los testigos y las v\u00edctimas participantes.<\/p>\n<p>Bachelet tambi\u00e9n habl\u00f3 de la guerra en Ucrania, de la que dijo que \u00abdejar\u00e1 una marca indeleble, tambi\u00e9n en las generaciones venideras\u00bb y destac\u00f3 que sus ramificaciones pol\u00edticas y sociales en todo el mundo \u201cno tienen final a la vista\u201d.<\/p>\n<p>Bachelet renuncia a un segundo mandato como Alta Comisionada<br \/>\nBachelet concluy\u00f3 su discurso anunciando que no se presentar\u00e1 a un segundo mandato como Alta Comisionada de la ONU y que la actual sesi\u00f3n del Consejo de Derechos Humanos ser\u00e1 la \u00faltima que dirija.<\/p>\n<p>Al conocerse la noticia, el Secretario General de la ONU emiti\u00f3 un comunicado donde le agradeci\u00f3 su incansable dedicaci\u00f3n a las Naciones Unidas como Alta Comisionada para los Derechos Humanos.<\/p>\n<p>\u201cEn todo lo que ha emprendido, Michelle Bachelet vive y respira derechos humanos. Ha conseguido cambiar la situaci\u00f3n en un contexto pol\u00edtico extremadamente dif\u00edcil, y ha marcado una profunda diferencia para las personas de todo el mundo\u201d, destac\u00f3 Ant\u00f3nio Guterres.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La m\u00e1xima responsable de derechos humanos de la ONU recuerda que 1200 millones de personas<\/p>\n","protected":false},"author":1,"featured_media":1574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[466],"tags":[468,967,968,966],"class_list":["post-1573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derechos-humanos-2","tag-bachelet","tag-disparidades","tag-marginacion","tag-michelle-bachelet"],"_links":{"self":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/comments?post=1573"}],"version-history":[{"count":1,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1573\/revisions"}],"predecessor-version":[{"id":1575,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1573\/revisions\/1575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media\/1574"}],"wp:attachment":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media?parent=1573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/categories?post=1573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/tags?post=1573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}