{"id":1695,"date":"2022-08-03T23:30:04","date_gmt":"2022-08-03T23:30:04","guid":{"rendered":"https:\/\/efectoambiental.org\/Noticias\/?p=1695"},"modified":"2022-08-03T23:30:04","modified_gmt":"2022-08-03T23:30:04","slug":"como-las-silenciosas-fugas-de-metano-agravan-el-cambio-climatico","status":"publish","type":"post","link":"https:\/\/efectoambiental.org\/Noticias\/2022\/08\/03\/como-las-silenciosas-fugas-de-metano-agravan-el-cambio-climatico\/","title":{"rendered":"C\u00f3mo las silenciosas fugas de metano agravan el cambio clim\u00e1tico"},"content":{"rendered":"<div>\n<div id=\"block-unep-3spot-content\">\n<article id=\"ThisOne\" role=\"article\" data-history-node-id=\"32327\">\n<div>\n<div>\n<div>\n<div class=\"paragraph paragraph--type--content paragraph--view-mode--default\">\n<div class=\"para_content_text\">\n<div>\n<p>Hay un secreto a voces en la industria del petr\u00f3leo y el gas que est\u00e1 agravando la crisis clim\u00e1tica.<\/p>\n<p>Se han producido fugas masivas de metano en todo el mundo, desde Estados Unidos hasta Turkmenist\u00e1n, que se conocen tambi\u00e9n como \u00absuperemisores\u00bb. Estos escapes enormes, que en su mayor\u00eda se deben a fallos en los equipos, pueden durar semanas. En 2015,\u00a0<a href=\"http:\/\/pubs.acs.org\/doi\/10.1021\/cen-09409-notw1\">una de las instalaciones de almacenamiento de gas natural en Los \u00c1ngeles arroj\u00f3<\/a>\u00a0a la atm\u00f3sfera un aproximado de\u00a0<a href=\"http:\/\/www.cpuc.ca.gov\/regulatory-services\/safety\/pipeline-safety\/aliso-canyon-well-failure\">100.000 toneladas de metano, un potente gas de efecto invernadero<\/a>, en el transcurso de cuatro meses.<\/p>\n<p>En junio de 2022, investigadores de la Universidad Polit\u00e9cnica de Valencia afirmaron haber descubierto el\u00a0<a href=\"http:\/\/www.esa.int\/Applications\/Observing_the_Earth\/Methane_emissions_detected_over_offshore_platform_in_the_Gulf_of_Mexico\">evento conocido m\u00e1s reciente de superemisi\u00f3n en una plataforma de petr\u00f3leo y gas en el Golfo de M\u00e9xico<\/a>. Dicha instalaci\u00f3n descarg\u00f3 40.000 toneladas de metano durante un per\u00edodo de 17 d\u00edas en diciembre de 2021, lo que equivale al 3% de las emisiones anuales de petr\u00f3leo y gas de M\u00e9xico. Los investigadores afirman que dicha cantidad podr\u00eda nunca haber sido de conocimiento p\u00fablico si no fuera porque fue captada por\u00a0<a href=\"http:\/\/www.esa.int\/Applications\/Observing_the_Earth\/Methane_emissions_detected_over_offshore_platform_in_the_Gulf_of_Mexico\">un sat\u00e9lite de la Agencia Espacial Europea<\/a>.<\/p>\n<p>Aunque el vertido fue captado, sigue siendo dif\u00edcil rastrear las emisiones de metano, un gas incoloro e inodoro y\u00a0<a href=\"https:\/\/www.unep.org\/es\/node\/30810\/\">responsable de m\u00e1s del 25% del calentamiento global<\/a>\u00a0que experimenta la Tierra en la actualidad. Debido a su estructura qu\u00edmica, el metano atrapa m\u00e1s calor en la atm\u00f3sfera por mol\u00e9cula que el di\u00f3xido de carbono (CO<sub>2<\/sub>), por lo que es 80 veces m\u00e1s da\u00f1ino que el CO<sub>2<\/sub>\u00a0durante los 20 a\u00f1os posteriores a su emisi\u00f3n a la atm\u00f3sfera.<\/p>\n<p>A medida que los pa\u00edses desarrollan planes para reducir las emisiones de gases de efecto invernadero y evitar las peores consecuencias del cambio clim\u00e1tico, los expertos y expertas afirman que es vital contar con un mejor control de la cantidad de metano que se libera a la atm\u00f3sfera, incluidos los eventos de superemisores. En efecto, si se reduce el metano antropog\u00e9nico (de origen humano)\u00a0<a href=\"https:\/\/www.unep.org\/es\/node\/29299\/\">en un 45% en este decenio<\/a>, se mantendr\u00eda el calentamiento por debajo del umbral establecido en el Acuerdo de Par\u00eds.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div class=\"quote_content\">\n<div class=\"quote_text\">\n<div>\n<p>El gran desaf\u00edo es saber exactamente cu\u00e1nto [metano] se est\u00e1 emitiendo, d\u00f3nde se est\u00e1 emitiendo y durante cu\u00e1nto tiempo se ha emitido.<\/p>\n<\/div>\n<\/div>\n<div class=\"quote_source\">\n<div>\n<div>Manfredi Caltagirone, PNUMA<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div class=\"paragraph paragraph--type--content paragraph--view-mode--default\">\n<div class=\"para_content_text\">\n<div>\n<p><strong>Una nueva base de datos de metano<\/strong><\/p>\n<p>Para rastrear y medir las emisiones de metano, el Programa de las Naciones Unidas para el Medio Ambiente inaugur\u00f3 en octubre de 2021 el\u00a0<a href=\"https:\/\/www.unep.org\/explore-topics\/energy\/what-we-do\/methane\">Observatorio Internacional de Emisiones de Metano<\/a>. Dicho observatorio cataloga los vertidos y fugas del sector de los combustibles f\u00f3siles, y pr\u00f3ximamente catalogar\u00e1 tambi\u00e9n los residuos y las liberaciones agr\u00edcolas.<\/p>\n<p>Las industrias del petr\u00f3leo y el gas son los principales productores de metano, puesto que emiten gas durante la perforaci\u00f3n, la producci\u00f3n y otras partes de sus operaciones. En determinadas ocasiones, el metano se libera intencionalmente de las instalaciones de petr\u00f3leo y gas por razones de seguridad.<\/p>\n<p>En contraste, el sector agr\u00edcola es otro gran emisor de metano, en particular la ganader\u00eda y el cultivo de ciertos alimentos, como el arroz. Los desechos son la tercera fuente m\u00e1s com\u00fan de metano antropog\u00e9nico, ya que las bacterias descomponen la materia org\u00e1nica en los vertederos.<\/p>\n<p>El Observatorio Internacional de Emisiones (IMEO) tiene como objetivo crear una base de datos p\u00fablicos de emisiones de metano verificadas emp\u00edricamente. En la actualidad, los pa\u00edses a menudo solo cuentan con estimaciones que a veces pueden ser varias magnitudes m\u00e1s inferiores que los niveles de emisiones reales.<\/p>\n<p>\u201cUna imagen m\u00e1s precisa de las emisiones de metano proporciona a los gobiernos y las empresas la informaci\u00f3n que necesitan para actuar con confianza\u201d, declar\u00f3 Mark Radka, Jefe de la Subdivisi\u00f3n de Energ\u00eda y Clima del PNUMA. \u00abEsto aplica tanto para las buenas pol\u00edticas como para las buenas pr\u00e1cticas de gesti\u00f3n\u00bb.<\/p>\n<p><strong>Medici\u00f3n del metano<\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure role=\"group\"><img decoding=\"async\" src=\"https:\/\/cdn.unenvironment.org\/s3fs-public\/inline-images\/methane_cow_measurement_germany.jpg\" alt=\" A cow and a researcher\t\" data-entity-type=\"file\" data-entity-uuid=\"85243354-3749-473f-99bf-a8e0a996b158\" \/><figcaption><em>Un investigador del Centro Agr\u00edcola de Baden-W\u00fcrttemberg en Alemania sostiene un detector que mide las emisiones de metano en el aire exhalado de las vacas. Foto: Reuters\/Thomas Warnack<\/em><\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>\u201cEl gran desaf\u00edo es saber exactamente cu\u00e1nto [metano] se est\u00e1 emitiendo, d\u00f3nde se est\u00e1 emitiendo y durante cu\u00e1nto tiempo se ha emitido para as\u00ed poder reducir las emisiones al nivel que necesitamos\u201d, declar\u00f3 Manfredi Caltagirone, director del Observatorio Internacional de Emisiones de Metano.<\/p>\n<p>La mejor manera de medir las emisiones de metano es mediante la combinaci\u00f3n de conocimientos operacionales y el uso de tecnolog\u00edas de cuantificaci\u00f3n de metano, drones y aeronaves equipadas con sensores.<\/p>\n<p>Asimismo, los sat\u00e9lites se est\u00e1n convirtiendo en un medio eficaz para detectar y medir las emisiones de metano enormes. Si bien el uso de sat\u00e9lites no siempre es pr\u00e1ctico, ya que las lecturas de metano pueden estar ocultas por condiciones ambientales como la cubierta de nubes, los bosques densos o la cubierta de nieve, son particularmente \u00fatiles para detectar y cuantificar eventos de superemisores como el del Golfo de M\u00e9xico. (Seg\u00fan conclusiones de las investigaciones, la fuga masiva habr\u00eda sido causada muy probablemente por un mal funcionamiento del equipamiento de las instalaciones).<\/p>\n<p>De hecho, el equipo de investigaci\u00f3n que descubri\u00f3 el evento superemisor en el Golfo de M\u00e9xico est\u00e1 en proceso de expandir su trabajo a sitios de producci\u00f3n de petr\u00f3leo y gas en zonas marinas ubicadas en otras partes del mundo.<\/p>\n<div class=\"inline-banner\">\n<div class=\"content_banner\"><\/div>\n<\/div>\n<p>Si los actuales inventarios de emisiones de metano son problem\u00e1ticos, \u00bfmerecen la pena? Para Giulia Ferrini, Oficial de Gesti\u00f3n de Programas del PNUMA, la respuesta es un rotundo s\u00ed, bajo la condici\u00f3n de que se implementen algunos cambios en la metodolog\u00eda.<\/p>\n<p>Seg\u00fan ella, mantener inventarios precisos y transparentes es fundamental para evitar el cambio clim\u00e1tico. Caltagirone y Ferrini argumentan que los inventarios de metano espec\u00edficos de cada lugar, o en el \u00e1mbito de activos, que se fundamentan en mediciones son un componente esencial de la mitigaci\u00f3n porque el\u00a0<a href=\"https:\/\/documents-dds-ny.un.org\/doc\/UNDOC\/LTD\/G15\/283\/22\/PDF\/G1528322.pdf?OpenElement\" target=\"_blank\" rel=\"noopener\">Acuerdo de Par\u00eds se basa en la transparencia y la rendici\u00f3n de cuentas<\/a>. La recopilaci\u00f3n de estos datos en el \u00e1mbito de activos proporciona la informaci\u00f3n necesaria a aquellos que tienen el poder decisorio de reducir las emisiones.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div class=\"paragraph paragraph--type--related-articles paragraph--view-mode--default\">\n<div>\n<div class=\"fieldTitle\">RELATED<\/div>\n<div>\n<div>\n<article class=\"stub_view\" role=\"article\" data-history-node-id=\"29858\">\n<div class=\"stub_view_wrap\">\n<div class=\"stub_view_left\"><a href=\"https:\/\/www.unep.org\/news-and-stories\/story\/methane-emissions-are-driving-climate-change-heres-how-reduce-them\" hreflang=\"en\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.unenvironment.org\/styles\/topics_content_promo\/s3\/2021-08\/Cattle.jpeg?itok=aFF2haEv\" alt=\"Cattle\" width=\"710\" height=\"397\" \/><\/a><\/div>\n<div class=\"stub_view_right\">\n<div class=\"stub_view_right_meta\">\n<div>REPORTAJES<\/div>\n<\/div>\n<div class=\"stub_view_right_title\"><a href=\"https:\/\/www.unep.org\/es\/noticias-y-reportajes\/reportajes\/las-emisiones-de-metano-estan-acelerando-el-cambio-climatico-como\" target=\"_blank\" rel=\"bookmark noopener\">Las emisiones de metano est\u00e1n acelerando el cambio clim\u00e1tico. \u00bfC\u00f3mo podemos reducirlas?<\/a><\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<div>\n<article class=\"stub_view\" lang=\"en\" role=\"article\" data-history-node-id=\"30014\">\n<div class=\"stub_view_wrap\">\n<div class=\"stub_view_left\"><a href=\"https:\/\/www.unep.org\/news-and-stories\/story\/new-global-methane-pledge-aims-tackle-climate-change\" hreflang=\"en\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.unenvironment.org\/styles\/topics_content_promo\/s3\/2021-09\/shutterstock_1103707850.jpeg?itok=AwYlEs8a\" alt=\"Fire flame \" width=\"710\" height=\"397\" \/><\/a><\/div>\n<div class=\"stub_view_right\">\n<div class=\"stub_view_right_meta\">\n<div>STORY<\/div>\n<\/div>\n<div class=\"stub_view_right_title\"><a href=\"https:\/\/www.unep.org\/news-and-stories\/story\/new-global-methane-pledge-aims-tackle-climate-change\" target=\"_blank\" rel=\"bookmark noopener\">New global methane pledge aims to tackle climate change<\/a><\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<div>\n<article class=\"stub_view\" role=\"article\" data-history-node-id=\"30379\">\n<div class=\"stub_view_wrap\">\n<div class=\"stub_view_left\"><a href=\"https:\/\/www.unep.org\/news-and-stories\/press-release\/methane-observatory-launched-boost-action-powerful-climate-warming\" hreflang=\"en\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.unenvironment.org\/styles\/topics_content_promo\/s3\/2021-10\/aerial-view-crude-oil-gas-terminal-loading-arm-oil-gas-refinery-commercial-port.jpg?itok=SzRyTGlA\" alt=\"Aerial View\" width=\"710\" height=\"397\" \/><\/a><\/div>\n<div class=\"stub_view_right\">\n<div class=\"stub_view_right_meta\">\n<div>COMUNICADO DE PRENSA<\/div>\n<\/div>\n<div class=\"stub_view_right_title\"><a href=\"https:\/\/www.unep.org\/es\/noticias-y-reportajes\/comunicado-de-prensa\/lanzan-el-observatorio-del-metano-para-impulsar-la\" target=\"_blank\" rel=\"bookmark noopener\">Lanzan el Observatorio del Metano para impulsar la acci\u00f3n sobre este poderoso gas que calienta el clima<\/a><\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div class=\"paragraph paragraph--type--content paragraph--view-mode--default\">\n<div class=\"para_content_text\">\n<div>\n<p>La\u00a0<a href=\"https:\/\/www.unep.org\/es\/noticias-y-reportajes\/comunicado-de-prensa\/empresas-petroleras-y-gasiferas-se-comprometen-reportar\" target=\"_blank\" rel=\"noopener\">Alianza para la reducci\u00f3n de las emisiones de metano provenientes de la producci\u00f3n de petr\u00f3leo y gas<\/a>\u00a02.0 (OGMP por sus siglas en ingl\u00e9s) consiste en un compromiso voluntario de las empresas vinculadas para medir y reportar sus emisiones de metano de fuentes como gasoductos, tanques de almacenamiento y plataformas petrol\u00edferas en alta mar. Este proceso les permite obtener mejores datos sobre los cuales actuar y concentrar los esfuerzos de mitigaci\u00f3n en sus lugares m\u00e1s contaminantes. Los datos del observatorio<br \/>\nIMEO tambi\u00e9n ayudar\u00e1n a rastrear el progreso del\u00a0<a href=\"https:\/\/www.globalmethanepledge.org\/\" target=\"_blank\" rel=\"noopener\">Compromiso Mundial de Reducci\u00f3n de Emisiones de Metano<\/a>. Esta iniciativa re\u00fane a m\u00e1s de 100 pa\u00edses comprometidos a reducir sus emisiones colectivas de metano en un 30% para 2030.<\/p>\n<p>Si es clave medir las emisiones rutinarias de metano en toda la cadena de suministro, \u00bfqu\u00e9 opini\u00f3n le merece a los eventos superemisores que a menudo pasan desapercibidos? \u00bfQu\u00e9 tan comunes son las fugas grandes como la que ocurri\u00f3 en el Golfo de M\u00e9xico y es posible prevenirlas?<\/p>\n<p>\u201cLa manera de detectar todas las emisiones, grandes y peque\u00f1as, es tener buenos reg\u00edmenes de seguimiento\u201d, afirm\u00f3 Mark Radka. \u201cHasta hace poco, no ten\u00edamos las herramientas para inspeccionar las emisiones de metano de forma independiente. Los sat\u00e9lites de hoy d\u00eda son eficaces para detectar grandes eventos de emisiones, y se est\u00e1n volviendo m\u00e1s precisos gracias a\u00a0 una mejor resoluci\u00f3n, pero no detectar\u00e1n las emisiones m\u00e1s peque\u00f1as. Es imperativo que contextualicemos esas grandes fuentes con respecto a las emisiones globales, puesto que muchas emisiones peque\u00f1as pueden ser igual de perjudiciales\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Acerca de la Coalici\u00f3n Clima y Aire Limpio<\/strong><\/p>\n<p>La Coalici\u00f3n Clima y Aire Limpio es una alianza voluntaria entre gobiernos, organizaciones gubernamentales, compa\u00f1\u00edas privadas, instituciones cient\u00edficas y organizaciones de la sociedad civil con el objetivo com\u00fan de proteger el clima y mejorar la calidad del aire a trav\u00e9s de acciones para reducir los contaminantes clim\u00e1ticos de vida corta, como el metano, el carbono negro, el ozono troposf\u00e9rico y los hidrofluorocarbonos (HFC). La Coalici\u00f3n cuenta con\u00a0<a title=\"Original URL: https:\/\/www.ccacoalition.org\/en\/partners. Click or tap if you trust this link.\" href=\"https:\/\/eur02.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.ccacoalition.org%2Fen%2Fpartners&amp;data=05%7C01%7Cclaudia.hihetah%40un.org%7C542313c9139946e12f4e08da6a6e3d3f%7C0f9e35db544f4f60bdcc5ea416e6dc70%7C0%7C0%7C637939318942344678%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000%7C%7C%7C&amp;sdata=uRFsX185Ox6SSF46zv7B9DSqerejFoJS5Vr%2BmWM9dPc%3D&amp;reserved=0\" target=\"_blank\" rel=\"noopener\">71 socios estatales y 78 no estatales<\/a>. En cuanto al metano, tiene iniciativas en los tres principales sectores emisores:\u00a0<a title=\"Original URL: https:\/\/www.ccacoalition.org\/en\/initiatives\/oil-gas. Click or tap if you trust this link.\" href=\"https:\/\/eur02.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.ccacoalition.org%2Fen%2Finitiatives%2Foil-gas&amp;data=05%7C01%7Cclaudia.hihetah%40un.org%7C542313c9139946e12f4e08da6a6e3d3f%7C0f9e35db544f4f60bdcc5ea416e6dc70%7C0%7C0%7C637939318942344678%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000%7C%7C%7C&amp;sdata=bQLnoSmPMPta6kEjf9YyI2Vnu6inOCyfzbyT20%2BbFXo%3D&amp;reserved=0\" target=\"_blank\" rel=\"noopener\">petr\u00f3leo y gas<\/a>,\u00a0<a title=\"Original URL: https:\/\/www.ccacoalition.org\/en\/initiatives\/waste. Click or tap if you trust this link.\" href=\"https:\/\/eur02.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.ccacoalition.org%2Fen%2Finitiatives%2Fwaste&amp;data=05%7C01%7Cclaudia.hihetah%40un.org%7C542313c9139946e12f4e08da6a6e3d3f%7C0f9e35db544f4f60bdcc5ea416e6dc70%7C0%7C0%7C637939318942344678%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000%7C%7C%7C&amp;sdata=B7QWQ5LPT6uJ5%2FtMd3Os4WcG%2BGU%2FYpXXRCKDGsquQEk%3D&amp;reserved=0\" target=\"_blank\" rel=\"noopener\">desechos<\/a>\u00a0y\u00a0<a title=\"Original URL: https:\/\/www.ccacoalition.org\/en\/initiatives\/agriculture. Click or tap if you trust this link.\" href=\"https:\/\/eur02.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.ccacoalition.org%2Fen%2Finitiatives%2Fagriculture&amp;data=05%7C01%7Cclaudia.hihetah%40un.org%7C542313c9139946e12f4e08da6a6e3d3f%7C0f9e35db544f4f60bdcc5ea416e6dc70%7C0%7C0%7C637939318942344678%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000%7C%7C%7C&amp;sdata=s5yxPEvIbsKepUxgoHz6vQXBSk9c%2FAQM0MWd2lg%2BNnk%3D&amp;reserved=0\" target=\"_blank\" rel=\"noopener\">agricultura<\/a>. La Secretar\u00eda de la Coalici\u00f3n es patrocinada por el Programa de las Naciones Unidas para el Medio Ambiente.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<div class=\"article_tags\"><span class=\"article_tags_title\">TEMAS<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hay un secreto a voces en la industria del petr\u00f3leo y el gas que est\u00e1<\/p>\n","protected":false},"author":1,"featured_media":1696,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[264],"tags":[225,504,1134,1133,1137,505,411,1136,1135],"class_list":["post-1695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cambio-climatico","tag-co2","tag-el-gas","tag-estados-unidos","tag-fugas-de-metano","tag-manfredi-caltagirone","tag-petroleo","tag-pnuma","tag-superemisores","tag-turkmenistan"],"_links":{"self":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/comments?post=1695"}],"version-history":[{"count":1,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1695\/revisions"}],"predecessor-version":[{"id":1697,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/1695\/revisions\/1697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media\/1696"}],"wp:attachment":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media?parent=1695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/categories?post=1695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/tags?post=1695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}