{"id":2060,"date":"2023-07-07T04:59:59","date_gmt":"2023-07-07T04:59:59","guid":{"rendered":"https:\/\/efectoambiental.org\/Noticias\/?p=2060"},"modified":"2023-07-07T05:01:16","modified_gmt":"2023-07-07T05:01:16","slug":"un-maremoto-toxico-de-plasticos-amenaza-los-derechos-humanos","status":"publish","type":"post","link":"https:\/\/efectoambiental.org\/Noticias\/2023\/07\/07\/un-maremoto-toxico-de-plasticos-amenaza-los-derechos-humanos\/","title":{"rendered":"Un \u201cmaremoto t\u00f3xico\u201d de pl\u00e1sticos amenaza los derechos humanos"},"content":{"rendered":"<div id=\"block-views-block-content-fields-block-lead\" class=\"views-element-container block block-views block-views-block-content-fields-block-lead\">\n<div class=\"content block__content\">\n<div>\n<div class=\"view view-content-fields view-id-content_fields view-display-id-block_lead js-view-dom-id-5180532e8f4135ddde8c41d3e568323905f21e1ede49a273196847a0baea2365\">\n<div class=\"view-content\">\n<div class=\"views-row\">\n<div class=\"views-field views-field-field-news-story-lead\">\n<div class=\"field-content\">\n<p>Cada a\u00f1o se generan 400 millones de toneladas de residuos pl\u00e1sticos y el 85% de los pl\u00e1sticos de un solo uso terminan en vertederos o contaminando r\u00edos, mares y paisajes. Expertos de la ONU exigen a los Estados y las empresas que asuman su responsabilidad y garanticen el derecho humano a un medio ambiente sano y libre de sustancias t\u00f3xicas.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"block-un-base-theme-content\" class=\"block block-system block-system-main-block block-un-base-theme-content\">\n<div class=\"content block__content\">\n<article class=\"node node--type-news-story node--view-mode-full clearfix\" role=\"article\">\n<header><\/header>\n<div class=\"node__content clearfix\"><\/div>\n<\/article>\n<\/div>\n<\/div>\n<div id=\"block-views-block-content-fields-block-body\" class=\"views-element-container block block-views block-views-block-content-fields-block-body\">\n<div class=\"content block__content\">\n<div>\n<div class=\"view view-content-fields view-id-content_fields view-display-id-block_body js-view-dom-id-858359f027a228655380fbb6c7005329bef2b723ca12dd8b38075e09181f12c9\">\n<div class=\"view-content\">\n<div class=\"views-row\">\n<div class=\"views-field views-field-field-news-story\">\n<div class=\"field-content\">\n<div class=\"paragraph paragraph--type--one-column-text paragraph--view-mode--default\">\n<div class=\"_none\">\n<div class=\"w-100\">\n<div class=\"layout row layout-builder__layout\">\n<div class=\"col-12\">\n<div class=\"_none block block-layout-builder block-field-block-paragraph-one-column-text-field-text-column\">\n<div class=\"content block__content\">\n<div class=\"clearfix text-formatted field field--name-field-text-column field--type-text-long field--label-hidden field__item\">\n<p>Expertos de la ONU* instan a los Estados a situar los derechos fundamentales en el centro del tratado internacional sobre la contaminaci\u00f3n causada por el pl\u00e1stico que se est\u00e1 negociando actualmente, y advierten de un \u00abmaremoto t\u00f3xico\u00bb sint\u00e9tico que contamina el planeta.<\/p>\n<p>En v\u00edsperas del D\u00eda Mundial del Medio Ambiente, dos expertos** han hecho referencia los 400 millones de toneladas de residuos de este material que se generan al a\u00f1o y han denunciado que todas las fases de su ciclo de vida tienen repercusiones negativas sobre los derechos humanos.<\/p>\n<p>\u201c<strong>La producci\u00f3n de pl\u00e1stico libera sustancias peligrosas<\/strong>\u00a0y depende casi exclusivamente de combustibles f\u00f3siles, mientras que el propio material contiene sustancias qu\u00edmicas t\u00f3xicas, lo que supone graves riesgos y da\u00f1os para la salud humana y el medio ambiente\u201d, han declarado los expertos.<\/p>\n<h2>Soluciones falsas y enga\u00f1osas<\/h2>\n<p>Adem\u00e1s, han explicado que al final de su ciclo como bien de consumo, sus residuos contaminan nuestro planeta, ya que\u00a0<strong>el 85% de los pl\u00e1sticos de un solo uso se env\u00edan a vertederos o se arrojan al medio ambiente<\/strong>. Las soluciones falsas y enga\u00f1osas, como la incineraci\u00f3n o el reciclado de este material lleno de t\u00f3xicos, agravan la situaci\u00f3n.<\/p>\n<p>Los expertos advierten que, en la actualidad, el pl\u00e1stico, los micropl\u00e1sticos y las sustancias peligrosas que contienen pueden encontrarse en los alimentos que comemos, el agua que bebemos y el aire que respiramos.<\/p>\n<p>Adem\u00e1s, la contribuci\u00f3n de este tipo de poluci\u00f3n al\u00a0<strong>cambio clim\u00e1tico<\/strong>\u00a0es alarmante, pero para los expertos, a menudo se pasa por alto. Un ejemplo es que las part\u00edculas de pl\u00e1stico que se encuentran en los oc\u00e9anos limitan la capacidad de los ecosistemas marinos para eliminar los gases de efecto invernadero de la atm\u00f3sfera.<\/p>\n<div class=\"align-center context-un_news_full_width_credit_caption type-entermedia_image media media--type-entermedia-image media--view-mode-un-news-full-width-credit-caption\" data-quickedit-entity-id=\"media\/58602\">\n<div class=\"field field--name-thumbnail field--type-image field--label-hidden field__item\"><img loading=\"lazy\" decoding=\"async\" title=\"Los filtros de cigarrillos contienen micropl\u00e1sticos y constituyen la segunda forma m\u00e1s alta de contaminaci\u00f3n con pl\u00e1sticos en el mundo.\" src=\"https:\/\/global.unitednations.entermediadb.net\/assets\/mediadb\/services\/module\/asset\/downloads\/preset\/Libraries\/Production%20Library\/02-02-2022-Unsplash-cigarette-butts-02.jpg\/image1170x530cropped.jpg\" alt=\"Los filtros de cigarrillos contienen micropl\u00e1sticos y constituyen la segunda forma m\u00e1s alta de contaminaci\u00f3n con pl\u00e1sticos en el mundo.\" width=\"1170\" height=\"530\" \/><\/div>\n<div class=\"field field--name-field-authors field--type-entity-reference field--label-hidden field__items\">\n<div class=\"field__item\">Unsplash\/Brian Yurasits<\/div>\n<\/div>\n<div class=\"field field--name-field-title field--type-string field--label-hidden field__item\">Los filtros de cigarrillos contienen micropl\u00e1sticos y constituyen la segunda forma m\u00e1s alta de contaminaci\u00f3n con pl\u00e1sticos en el mundo.<\/div>\n<\/div>\n<h2>Zonas de sacrifico<\/h2>\n<p>\u201cAunque todo el mundo se ve afectado por las repercusiones negativas del pl\u00e1stico, el nivel de exposici\u00f3n a la contaminaci\u00f3n y sus residuos afectan m\u00e1s a las comunidades marginadas\u201d, declaran los expertos.<\/p>\n<p>Es especialmente preocupante la situaci\u00f3n de los grupos que est\u00e1n expuestos a una mayor exposici\u00f3n a la contaminaci\u00f3n por pl\u00e1sticos y a injusticias medioambientales al habitar las llamadas \u00abzonas de sacrificio\u00bb.<\/p>\n<p>Estas zonas son lugares donde se han establecido f\u00e1bricas, minas y refiner\u00edas cuyas actividades han liberado un alto contenido de sustancias t\u00f3xicas, contaminando el aire, el suelo y el agua, y amenazando la salud de las personas que viven en las cercan\u00edas.<\/p>\n<p>Los expertos expusieron en un\u00a0<a href=\"https:\/\/www.ohchr.org\/sites\/default\/files\/2022-03\/SacrificeZones-userfriendlyversion.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">informe<\/a>\u00a0distintos casos a nivel global. En la regi\u00f3n de Am\u00e9rica y el Caribe, hicieron referencia a zonas como La Oroya, Per\u00fa, donde el 99% de los ni\u00f1os presentan\u00a0<strong>niveles elevados de plomo en la sangre\u00a0<\/strong>al vivir cerca de una fundidora de plomo.<\/p>\n<p>El informe se\u00f1ala adem\u00e1s que comunidades ind\u00edgenas Wayu\u00fa, en Colombia, sufren de\u00a0<strong>enfermedades respiratorias y elevados niveles de sustancias t\u00f3xicas en la sangre<\/strong>\u00a0ante la contaminaci\u00f3n y el agua por la mina de carb\u00f3n de El Cerrej\u00f3n.<\/p>\n<p>La extracci\u00f3n de petr\u00f3leo ha contaminado las aguas de zonas como Vaca Muerta, en Argentina, y la falta de mantenimiento de las refiner\u00edas en Venezuela ha dejado a la poblaci\u00f3n expuesta a\u00a0<strong>derrames petrol\u00edferos<\/strong>\u00a0en zonas como Paraguan\u00e1.<\/p>\n<h2>Derecho a un medio ambiente sano<\/h2>\n<p>\u201cResulta estremecedor comprobar c\u00f3mo la omnipresencia de los pl\u00e1sticos repercute en los derechos humanos de muy diversas maneras, como el derecho a un medio ambiente sano, a la vida, a la salud, a la alimentaci\u00f3n, al agua y a un nivel de vida adecuado\u201d, defienden los expertos.<\/p>\n<p>En este sentido, recuerdan que\u00a0<strong>los Estados y las empresas tienen obligaciones<\/strong>\u00a0espec\u00edficas en materia de derechos fundamentales que se aplican en el contexto de la lucha contra la contaminaci\u00f3n por pl\u00e1sticos.<\/p>\n<p>Por ejemplo, en los dos \u00faltimos a\u00f1os, el Consejo de Derechos Humanos y la\u00a0<a href=\"https:\/\/www.un.org\/es\/ga\/about\/index.shtml\">Asamblea General<\/a>\u00a0de la ONU adoptaron resoluciones hist\u00f3ricas que reconocen el\u00a0<strong>derecho humano a un medio ambiente limpio, sano y sostenible<\/strong>, lo que incluye entornos no t\u00f3xicos en los que las personas puedan vivir, trabajar, estudiar y jugar.<\/p>\n<p>Esto deber\u00eda impulsar las iniciativas para hacer frente a la situaci\u00f3n, aseguraron los expertos, quienes acogieron con satisfacci\u00f3n los avances de los Estados en la formulaci\u00f3n de una\u00a0<strong>regulaci\u00f3n global e internacionalmente vinculante<\/strong>\u00a0e instaron a que se complete a finales de 2024.<\/p>\n<p>\u201cEs urgente dar prioridad a la reducci\u00f3n de la producci\u00f3n y el uso del pl\u00e1stico, a la desintoxicaci\u00f3n y a la reducci\u00f3n de las emisiones de gases de efecto invernadero\u201d, finalizaron.<\/p>\n<p><em>*<\/em><em>Los relatores especiales forman parte de lo que se conoce como\u00a0<\/em><a href=\"https:\/\/www.ohchr.org\/es\/special-procedures-human-rights-council\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Procedimientos Especiales<\/em><\/a><em>\u00a0del\u00a0<\/em><em><a href=\"https:\/\/www.ohchr.org\/SP\/HRBodies\/HRC\/Pages\/Home.aspx\" target=\"_blank\" rel=\"noopener noreferrer\">Consejo de Derechos Humanos<\/a><\/em><em>. Procedimientos Especiales, el mayor \u00f3rgano de expertos independientes del sistema de derechos humanos de la ONU, es el nombre general de los mecanismos independientes de investigaci\u00f3n y supervisi\u00f3n del Consejo que se ocupan de situaciones espec\u00edficas de pa\u00edses o de cuestiones tem\u00e1ticas en todas las partes del mundo. Los expertos de los Procedimientos Especiales trabajan de forma voluntaria; no son personal de la ONU y no reciben un salario por su trabajo. Son independientes de cualquier gobierno u organizaci\u00f3n y prestan sus servicios a t\u00edtulo individual.<\/em><\/p>\n<p><em>Los expertos** son: David R. Boyd, relator especial sobre derechos humanos y medio ambiente; Marcos Orellana, relator especial sobre t\u00f3xicos y derechos humanos.<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"block-views-block-content-footer-block-1\" class=\"views-element-container block block-views block-views-block-content-footer-block-1\">\n<div class=\"content block__content\">\n<div>\n<div class=\"view view-content-footer view-id-content_footer view-display-id-block_1 js-view-dom-id-a1627df3bebfe4026d431b7d682b049b423e16bd46f01ce994641bc9bda28bcd\">\n<div class=\"view-content\">\n<div class=\"views-row\">\n<article class=\"node node--type-promo-banner node--view-mode-default clearfix\" role=\"article\">\n<div class=\"node__content clearfix\">\n<div class=\"clearfix text-formatted field field--name-body field--type-text-with-summary field--label-hidden field__item\">\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cada a\u00f1o se generan 400 millones de toneladas de residuos pl\u00e1sticos y el 85% de<\/p>\n","protected":false},"author":1,"featured_media":2062,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[264,1],"tags":[1514,469,1511,1512,1513,591,1466],"class_list":["post-2060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cambio-climatico","category-uncategorized","tag-contaminando","tag-derechos-humanos","tag-maremoto-toxico","tag-mares","tag-paisajes","tag-plasticos","tag-rios"],"_links":{"self":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/2060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/comments?post=2060"}],"version-history":[{"count":1,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/2060\/revisions"}],"predecessor-version":[{"id":2061,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/2060\/revisions\/2061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media\/2062"}],"wp:attachment":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media?parent=2060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/categories?post=2060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/tags?post=2060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}