{"id":803,"date":"2021-07-01T03:19:55","date_gmt":"2021-07-01T03:19:55","guid":{"rendered":"https:\/\/efectoambiental.org\/Noticias\/?p=803"},"modified":"2021-07-01T03:19:55","modified_gmt":"2021-07-01T03:19:55","slug":"emisiones-de-vehiculos","status":"publish","type":"post","link":"https:\/\/efectoambiental.org\/Noticias\/2021\/07\/01\/emisiones-de-vehiculos\/","title":{"rendered":"Emisiones de veh\u00edculos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Las emisiones de veh\u00edculos se dividen en cinco categor\u00edas principales:<br \/>\n<img decoding=\"async\" src=\"https:\/\/www.oica.net\/wp-content\/uploads\/2007\/07\/CO2-Icon.gif\" alt=\"Carbon Dioxide (CO2)\" \/>Di\u00f3xido de carbono (CO2) Di\u00f3xido de carbono (CO2), que es un producto inevitable de la quema de un combustible que contiene carbono (como lo hacen todos los productos del petr\u00f3leo). El CO2 no contamina el aire que respiramos, pero es uno de los principales contribuyentes al calentamiento global y, por lo tanto, debe reducirse. Esto significa utilizar combustibles que contengan menos (o ning\u00fan) carbono (consulte la secci\u00f3n sobre combustibles alternativos) o hacer que los veh\u00edculos y sus motores sean m\u00e1s eficientes, o ambas cosas.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.oica.net\/wp-content\/uploads\/2007\/07\/CO-Icon.gif\" alt=\"Carbon Monoxide (CO)\" \/> de carbono (CO) Mon\u00f3xido de carbono (CO), que se produce cuando un combustible a base de carbono se quema de forma incompleta. En altas concentraciones es venenoso y debe controlarse. Puede reducirse mediante una combusti\u00f3n m\u00e1s eficiente en el motor (de modo que se produzca CO2 en lugar de CO) y reducirse a\u00fan m\u00e1s oxidando despu\u00e9s de la combusti\u00f3n, en un convertidor catal\u00edtico. [2xCO + O2 = 2xCO2]<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.oica.net\/wp-content\/uploads\/2007\/07\/HC-Icon.gif\" alt=\"Hydrocarbons (HC)\" \/>Hidrocarburos (HC) Los hidrocarburos (HC), tambi\u00e9n conocidos como \u201ccompuestos org\u00e1nicos vol\u00e1tiles (COV), son en realidad combustibles no quemados. Pueden ser un problema para las personas con dificultades respiratorias y contribuyen al \u00absmog fotoqu\u00edmico\u00bb en determinadas condiciones clim\u00e1ticas. Pueden reducirse mediante una combusti\u00f3n m\u00e1s eficiente en el motor y reducirse a\u00fan m\u00e1s oxidando despu\u00e9s de la combusti\u00f3n, en un convertidor catal\u00edtico. . [4HxCy + (x + 4y) O2 = 2xH2O + 4yCO2]<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.oica.net\/wp-content\/uploads\/2007\/07\/NOx-Icon.gif\" alt=\"Oxides of Nitrogen (NOx)\" \/>\u00d3xidos de nitr\u00f3geno (NOx) Los \u00f3xidos de nitr\u00f3geno (NOx) se producen cuando el aire (que es principalmente una mezcla de nitr\u00f3geno y ox\u00edgeno) se calienta como en un motor. El NOx contribuye tanto al smog fotoqu\u00edmico como a la lluvia \u00e1cida y puede irritar los pulmones. A diferencia del CO y el HC, no se puede eliminar por oxidaci\u00f3n. El proceso opuesto: la eliminaci\u00f3n de ox\u00edgeno, conocida como \u00abreducci\u00f3n\u00bb, es necesaria para convertirlo de nuevo en nitr\u00f3geno y ox\u00edgeno.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.oica.net\/wp-content\/uploads\/2007\/07\/PM-Icon.gif\" alt=\"Particulate Matter (PM)\" \/>Material particularizado (PM) El material particularizado (PM) son part\u00edculas muy peque\u00f1as, en su mayor\u00eda de carbono no quemado.<\/p>\n<p>&nbsp;<\/p>\n<p>Datos sobre las pruebas de emisiones de autom\u00f3viles: todo lo que necesita saber sobre las pruebas de emisiones<br \/>\nEl nuevo sitio web CarEmissionsTestingFacts.eu proporciona una descripci\u00f3n general basada en hechos sobre todo lo relacionado con la prueba de emisiones de autom\u00f3viles en Europa.<\/p>\n<p>A trav\u00e9s de varias infograf\u00edas, esta plataforma en l\u00ednea proporciona respuestas claras a las preguntas m\u00e1s comunes sobre las pruebas de emisiones, y cada explicaci\u00f3n se complementa con informaci\u00f3n de fondo detallada. Las preguntas incluyen: qu\u00e9 son las emisiones, c\u00f3mo se miden (NEDC, WLTP y RDE) y el progreso que se ha logrado para reducirlas.<\/p>\n<p>Basado en hechos, este sitio web tambi\u00e9n tiene como objetivo informar al lector correctamente y abordar los conceptos err\u00f3neos comunes sobre la industria del autom\u00f3vil y las emisiones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Las emisiones de veh\u00edculos se dividen en cinco categor\u00edas principales: Di\u00f3xido de carbono (CO2)<\/p>\n","protected":false},"author":1,"featured_media":804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[220,238],"tags":[239],"class_list":["post-803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emisiones","category-vehiculos","tag-emisiones-de-vehiculos"],"_links":{"self":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/comments?post=803"}],"version-history":[{"count":1,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/803\/revisions"}],"predecessor-version":[{"id":805,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/posts\/803\/revisions\/805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media\/804"}],"wp:attachment":[{"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/media?parent=803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/categories?post=803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efectoambiental.org\/Noticias\/wp-json\/wp\/v2\/tags?post=803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}